{"id":239,"date":"2021-08-25T02:16:38","date_gmt":"2021-08-25T02:16:38","guid":{"rendered":"https:\/\/rysa.com.co\/index.php\/about\/"},"modified":"2023-10-19T08:00:05","modified_gmt":"2023-10-19T13:00:05","slug":"about","status":"publish","type":"page","link":"https:\/\/rysa.com.co\/index.php\/about\/","title":{"rendered":"Nosotros"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"239\" class=\"elementor elementor-239\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7d801d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7d801d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1897415\" data-id=\"1897415\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e577a9c elementor-widget elementor-widget-heading\" data-id=\"e577a9c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">conoce mas de<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32cd5c7 elementor-widget elementor-widget-heading\" data-id=\"32cd5c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nosotros<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-756bf45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"756bf45\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b0da95\" data-id=\"4b0da95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-97f4590 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97f4590\" data-element_type=\"section\" id=\"empresa\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3c1949c\" data-id=\"3c1949c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff455e3 elementor-widget elementor-widget-heading\" data-id=\"ff455e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">recursos y soluciones arqutectonicas rys-a<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37261ef elementor-widget elementor-widget-heading\" data-id=\"37261ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra Empresa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2097c9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a2097c9\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6e053df\" data-id=\"6e053df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dac2396 elementor-widget elementor-widget-image-carousel\" data-id=\"dac2396\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/pedro-miranda-3QzMBrvCeyQ-unsplash-scaled.jpg\" alt=\"pedro-miranda-3QzMBrvCeyQ-unsplash\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/krakenimages-Y5bvRlcCx8k-unsplash-scaled.jpg\" alt=\"krakenimages-Y5bvRlcCx8k-unsplash\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/ryan-ancill-RfCKKTmOtyQ-unsplash-scaled.jpg\" alt=\"ryan-ancill-RfCKKTmOtyQ-unsplash\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2869dd0\" data-id=\"2869dd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe84a38 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fe84a38\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad47d0 elementor-widget elementor-widget-text-editor\" data-id=\"5ad47d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-style: inherit; font-weight: inherit; background-color: var( --e-global-color-astglobalcolor5 ); color: var(--ast-global-color-3);\">Recursos y Soluciones Arquitect\u00f3nicas<br \/>S.A.S re\u00fane la experiencia adquirida por<br \/>m\u00e1s de veintid\u00f3s (22) a\u00f1os de servicio<br \/>continuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.<\/span><\/p><p>Apoyados en los valores compartidos<br \/>con nuestros clientes y nuestro equipo de trabajo, hemos logrado a traves del tiempo, consolidar y fortalecer\u00a0 las actividades objeto de nuestro trabajo.<\/p><p>Queremos ser su mejor alternativa en la toma de decisiones, acerca de los servicios que estamos en capacidad de asumir; as\u00ed como tambi\u00e9n ser su aliado integral en las ideas y necesidades que nos planteen.<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5634ad elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"d5634ad\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spa\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInnovaci\u00f3n en Dise\u00f1o\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span style=\"color: rgb(55, 65, 81); font-family: S\u00f6hne, ui-sans-serif, system-ui, -apple-system, &quot;Segoe UI&quot;, Roboto, Ubuntu, Cantarell, &quot;Noto Sans&quot;, sans-serif, &quot;Helvetica Neue&quot;, Arial, &quot;Apple Color Emoji&quot;, &quot;Segoe UI Emoji&quot;, &quot;Segoe UI Symbol&quot;, &quot;Noto Color Emoji&quot;; font-size: 16px; text-align: left; background-color: rgb(247, 247, 248);\">Detalles que Marcan la Diferencia<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4163b78 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"4163b78\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hands\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConstrucci\u00f3n de Sue\u00f1os\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span style=\"color: rgb(55, 65, 81); font-family: S\u00f6hne, ui-sans-serif, system-ui, -apple-system, &quot;Segoe UI&quot;, Roboto, Ubuntu, Cantarell, &quot;Noto Sans&quot;, sans-serif, &quot;Helvetica Neue&quot;, Arial, &quot;Apple Color Emoji&quot;, &quot;Segoe UI Emoji&quot;, &quot;Segoe UI Symbol&quot;, &quot;Noto Color Emoji&quot;; font-size: 16px; text-align: left; background-color: rgb(247, 247, 248);\">Dando Forma a Tus Sue\u00f1os, Ladrillo a Ladrillo.<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47401ba elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"47401ba\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tExcelencia en Cada Detalle\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNuestra Experiencia a tu alcance.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0107426 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0107426\" data-element_type=\"section\" id=\"valores\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24863f6\" data-id=\"24863f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d6214ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6214ef\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b823f03\" data-id=\"b823f03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a873fe elementor-widget elementor-widget-heading\" data-id=\"9a873fe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">recursos y soluciones arqutectonicas rys-a<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8407b74 elementor-widget elementor-widget-heading\" data-id=\"8407b74\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros Valores<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a82a34d\" data-id=\"a82a34d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-350df7a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"350df7a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90f33e1 elementor-widget elementor-widget-text-editor\" data-id=\"90f33e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t&nbsp;\n\n<style>\n  ul {\n    list-style: none;\n    padding: 0;\n  }\nli.valores::before {\n    content: \"\";\n    display: inline-block;\n    width: 15px; \/* Ancho del cuadrado *\/\n    height: 15px; \/* Altura del cuadrado *\/\n    background-color: #FFB100; \/* Color amarillo *\/\n    margin-right: 10px; \/* Espacio entre el cuadrado y el texto *\/\n  }\n<\/style>\n\n&nbsp;\n<ul>\n \t<li class=\"valores\">Actuamos con <strong>INTEGRIDAD<\/strong><\/li>\n \t<li class=\"valores\">Trabajamos en <strong>EQUIPO<\/strong><\/li>\n \t<li class=\"valores\"><strong>RESPETAMOS<\/strong> a las personas<\/li>\n \t<li class=\"valores\">Nos <strong>COMUNICAMOS<\/strong> Abierta y Honestamente<\/li>\n \t<li class=\"valores\">Hacemos Bien las cosas para <strong>NUESTROS CLIENTES<\/strong><\/li>\n<\/ul>\n&nbsp;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-sb8ek2s elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"sb8ek2s\" data-element_type=\"section\" id=\"mision\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5fcceb3\" data-id=\"5fcceb3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1726a4d elementor-widget elementor-widget-image\" data-id=\"1726a4d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/services-4.jpg\" class=\"attachment-full size-full wp-image-1017\" alt=\"\" srcset=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/services-4.jpg 700w, https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/services-4-300x214.jpg 300w, https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/services-4-162x116.jpg 162w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-04229e9\" data-id=\"04229e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b13246 elementor-widget elementor-widget-heading\" data-id=\"8b13246\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">recursos y soluciones arqutectonicas rys-a<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdb5955 elementor-widget elementor-widget-heading\" data-id=\"bdb5955\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Misi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1bbbe1 elementor-widget elementor-widget-text-editor\" data-id=\"b1bbbe1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Transformar el conocimiento y la experiencia en beneficios que nos permitan atender las necesidades de nuestros clientes, brindando servicios y productos de calidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-crb8219 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"crb8219\" data-element_type=\"section\" id=\"vision\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b0b74d8\" data-id=\"b0b74d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5ed197 elementor-widget elementor-widget-heading\" data-id=\"a5ed197\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">recursos y soluciones arquitectonicas rys-a<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfed4c6 elementor-widget elementor-widget-heading\" data-id=\"bfed4c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-327f367 elementor-widget elementor-widget-text-editor\" data-id=\"327f367\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ser la empresa LIDER y ALIADA de nuestros clientes en el mercado del cual hacemos parte<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51962fb\" data-id=\"51962fb\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6315460 elementor-widget elementor-widget-image\" data-id=\"6315460\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/services-2.jpg\" class=\"attachment-full size-full wp-image-1016\" alt=\"\" srcset=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/services-2.jpg 700w, https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/services-2-300x214.jpg 300w, https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/services-2-162x116.jpg 162w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-x78bcus elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"x78bcus\" data-element_type=\"section\" id=\"clientes\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b6017f\" data-id=\"4b6017f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dbdd0e elementor-widget elementor-widget-heading\" data-id=\"3dbdd0e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Algunos de Nuestros Clientes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc0b37c elementor-arrows-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"fc0b37c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/SWA_colombia_presto_redes_sociales_paginas_de_internet-465x270-1.jpg\" alt=\"SWA_colombia_presto_redes_sociales_paginas_de_internet-465x270\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/soportica.png\" alt=\"soportica\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/Davivienda.png\" alt=\"Davivienda\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logo-Universidad-Nacional-1.png\" alt=\"logo-Universidad-Nacional\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logop1-1.jpg\" alt=\"logop1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/pasion.png\" alt=\"pasion\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/colfondos.jpg\" alt=\"colfondos\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/gimnasio-horizontes.jpg\" alt=\"gimnasio horizontes\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/pizza.png\" alt=\"pizza\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/licochco.png\" alt=\"licochco\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\u00f3nicasS.A.S re\u00fane la experiencia adquirida porm\u00e1s de veintid\u00f3s (22) a\u00f1os de serviciocontinuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero. Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\u00f3nicasS.A.S re\u00fane la experiencia adquirida porm\u00e1s de veintid\u00f3s (22) a\u00f1os de serviciocontinuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, hemos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/rysa.com.co\/index.php\/about\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"RS Arquitectonicas - Recursos y Soluciones Arquitectonicas S.A.S\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nosotros - RS Arquitectonicas\" \/>\n\t\t<meta property=\"og:description\" content=\"conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\u00f3nicasS.A.S re\u00fane la experiencia adquirida porm\u00e1s de veintid\u00f3s (22) a\u00f1os de serviciocontinuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, hemos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/rysa.com.co\/index.php\/about\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logotipo-02.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logotipo-02.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-25T02:16:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-19T13:00:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nosotros - RS Arquitectonicas\" \/>\n\t\t<meta name=\"twitter:description\" content=\"conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\u00f3nicasS.A.S re\u00fane la experiencia adquirida porm\u00e1s de veintid\u00f3s (22) a\u00f1os de serviciocontinuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, hemos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logotipo-02.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rysa.com.co\\\/index.php\\\/about\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rysa.com.co#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rysa.com.co\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rysa.com.co\\\/index.php\\\/about\\\/#listItem\",\"name\":\"Nosotros\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rysa.com.co\\\/index.php\\\/about\\\/#listItem\",\"position\":2,\"name\":\"Nosotros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rysa.com.co#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rysa.com.co\\\/#organization\",\"name\":\"RS Arquitectonicas\",\"description\":\"Recursos y Soluciones Arquitectonicas S.A.S\",\"url\":\"https:\\\/\\\/rysa.com.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/rysa.com.co\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logotipo-02.jpg\",\"@id\":\"https:\\\/\\\/rysa.com.co\\\/index.php\\\/about\\\/#organizationLogo\",\"width\":284,\"height\":284,\"caption\":\"Logo Recursos y Soluciones Arquitectonicas\"},\"image\":{\"@id\":\"https:\\\/\\\/rysa.com.co\\\/index.php\\\/about\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rysa.com.co\\\/index.php\\\/about\\\/#webpage\",\"url\":\"https:\\\/\\\/rysa.com.co\\\/index.php\\\/about\\\/\",\"name\":\"Nosotros - RS Arquitectonicas\",\"description\":\"conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\\u00f3nicasS.A.S re\\u00fane la experiencia adquirida porm\\u00e1s de veintid\\u00f3s (22) a\\u00f1os de serviciocontinuo a la empresa privada, p\\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, hemos\",\"inLanguage\":\"es-CO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rysa.com.co\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rysa.com.co\\\/index.php\\\/about\\\/#breadcrumblist\"},\"datePublished\":\"2021-08-25T02:16:38-05:00\",\"dateModified\":\"2023-10-19T08:00:05-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rysa.com.co\\\/#website\",\"url\":\"https:\\\/\\\/rysa.com.co\\\/\",\"name\":\"RS Arquitectonicas\",\"description\":\"Recursos y Soluciones Arquitectonicas S.A.S\",\"inLanguage\":\"es-CO\",\"publisher\":{\"@id\":\"https:\\\/\\\/rysa.com.co\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nosotros - RS Arquitectonicas","description":"conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\u00f3nicasS.A.S re\u00fane la experiencia adquirida porm\u00e1s de veintid\u00f3s (22) a\u00f1os de serviciocontinuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, hemos","canonical_url":"https:\/\/rysa.com.co\/index.php\/about\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/rysa.com.co\/index.php\/about\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/rysa.com.co#listItem","position":1,"name":"Home","item":"https:\/\/rysa.com.co","nextItem":{"@type":"ListItem","@id":"https:\/\/rysa.com.co\/index.php\/about\/#listItem","name":"Nosotros"}},{"@type":"ListItem","@id":"https:\/\/rysa.com.co\/index.php\/about\/#listItem","position":2,"name":"Nosotros","previousItem":{"@type":"ListItem","@id":"https:\/\/rysa.com.co#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/rysa.com.co\/#organization","name":"RS Arquitectonicas","description":"Recursos y Soluciones Arquitectonicas S.A.S","url":"https:\/\/rysa.com.co\/","logo":{"@type":"ImageObject","url":"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logotipo-02.jpg","@id":"https:\/\/rysa.com.co\/index.php\/about\/#organizationLogo","width":284,"height":284,"caption":"Logo Recursos y Soluciones Arquitectonicas"},"image":{"@id":"https:\/\/rysa.com.co\/index.php\/about\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/rysa.com.co\/index.php\/about\/#webpage","url":"https:\/\/rysa.com.co\/index.php\/about\/","name":"Nosotros - RS Arquitectonicas","description":"conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\u00f3nicasS.A.S re\u00fane la experiencia adquirida porm\u00e1s de veintid\u00f3s (22) a\u00f1os de serviciocontinuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, hemos","inLanguage":"es-CO","isPartOf":{"@id":"https:\/\/rysa.com.co\/#website"},"breadcrumb":{"@id":"https:\/\/rysa.com.co\/index.php\/about\/#breadcrumblist"},"datePublished":"2021-08-25T02:16:38-05:00","dateModified":"2023-10-19T08:00:05-05:00"},{"@type":"WebSite","@id":"https:\/\/rysa.com.co\/#website","url":"https:\/\/rysa.com.co\/","name":"RS Arquitectonicas","description":"Recursos y Soluciones Arquitectonicas S.A.S","inLanguage":"es-CO","publisher":{"@id":"https:\/\/rysa.com.co\/#organization"}}]},"og:locale":"es_ES","og:site_name":"RS Arquitectonicas - Recursos y Soluciones Arquitectonicas S.A.S","og:type":"article","og:title":"Nosotros - RS Arquitectonicas","og:description":"conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\u00f3nicasS.A.S re\u00fane la experiencia adquirida porm\u00e1s de veintid\u00f3s (22) a\u00f1os de serviciocontinuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, hemos","og:url":"https:\/\/rysa.com.co\/index.php\/about\/","og:image":"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logotipo-02.jpg","og:image:secure_url":"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logotipo-02.jpg","article:published_time":"2021-08-25T02:16:38+00:00","article:modified_time":"2023-10-19T13:00:05+00:00","twitter:card":"summary_large_image","twitter:title":"Nosotros - RS Arquitectonicas","twitter:description":"conoce mas de Nosotros recursos y soluciones arqutectonicas rys-a Nuestra Empresa Recursos y Soluciones Arquitect\u00f3nicasS.A.S re\u00fane la experiencia adquirida porm\u00e1s de veintid\u00f3s (22) a\u00f1os de serviciocontinuo a la empresa privada, p\u00fablica y particulares en general; actividad que desarrolla principalmente en el Eje Cafetero.Apoyados en los valores compartidoscon nuestros clientes y nuestro equipo de trabajo, hemos","twitter:image":"https:\/\/rysa.com.co\/wp-content\/uploads\/2023\/10\/logotipo-02.jpg"},"aioseo_meta_data":{"post_id":"239","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-05 15:29:22","updated":"2025-06-04 08:33:35","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/rysa.com.co\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNosotros\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/rysa.com.co"},{"label":"Nosotros","link":"https:\/\/rysa.com.co\/index.php\/about\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/rysa.com.co\/index.php\/wp-json\/wp\/v2\/pages\/239"}],"collection":[{"href":"https:\/\/rysa.com.co\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rysa.com.co\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rysa.com.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rysa.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=239"}],"version-history":[{"count":74,"href":"https:\/\/rysa.com.co\/index.php\/wp-json\/wp\/v2\/pages\/239\/revisions"}],"predecessor-version":[{"id":1246,"href":"https:\/\/rysa.com.co\/index.php\/wp-json\/wp\/v2\/pages\/239\/revisions\/1246"}],"wp:attachment":[{"href":"https:\/\/rysa.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}